{"id":2562,"count":0,"description":"","link":"https:\/\/www.bikemate.net\/en\/tag\/touring-helmet\/","name":"Touring helmet","slug":"touring-helmet","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Touring helmet &#183; BIKEMATE.NET \u0e0a\u0e49\u0e2d\u0e1b\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 | GIVI | FIVE advanced Gloves | DAYTONA | TANAX<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Touring helmet &#183; BIKEMATE.NET \u0e0a\u0e49\u0e2d\u0e1b\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 | GIVI | FIVE advanced Gloves | DAYTONA | TANAX\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bikemate.net\/en\/tag\/touring-helmet\/\" \/>\n<meta property=\"og:site_name\" content=\"BIKEMATE.NET \u0e0a\u0e49\u0e2d\u0e1b\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 | GIVI | FIVE advanced Gloves | DAYTONA | TANAX\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bikemate.net\/wp-content\/uploads\/2020\/09\/bikemate-social-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@bikematenet\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.bikemate.net\/en\/tag\/touring-helmet\/\",\"url\":\"https:\/\/www.bikemate.net\/en\/tag\/touring-helmet\/\",\"name\":\"Touring helmet &#183; BIKEMATE.NET \u0e0a\u0e49\u0e2d\u0e1b\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 | GIVI | FIVE advanced Gloves | DAYTONA | TANAX\",\"isPartOf\":{\"@id\":\"https:\/\/www.bikemate.net\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.bikemate.net\/en\/tag\/touring-helmet\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bikemate.net\/en\/tag\/touring-helmet\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bikemate.net\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Touring helmet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bikemate.net\/en\/#website\",\"url\":\"https:\/\/www.bikemate.net\/en\/\",\"name\":\"BIKEMATE.NET\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bikemate.net\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bikemate.net\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bikemate.net\/en\/#organization\",\"name\":\"BIKEMATE.NET\",\"url\":\"https:\/\/www.bikemate.net\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.bikemate.net\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bikemate.net\/wp-content\/uploads\/2020\/07\/bikemate-logo-bigbg.png\",\"contentUrl\":\"https:\/\/www.bikemate.net\/wp-content\/uploads\/2020\/07\/bikemate-logo-bigbg.png\",\"width\":460,\"height\":116,\"caption\":\"BIKEMATE.NET\"},\"image\":{\"@id\":\"https:\/\/www.bikemate.net\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/BIKEMATE.NET\/\",\"https:\/\/x.com\/bikematenet\",\"https:\/\/www.instagram.com\/bikematenet\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Touring helmet &#183; BIKEMATE.NET \u0e0a\u0e49\u0e2d\u0e1b\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 | GIVI | FIVE advanced Gloves | DAYTONA | TANAX","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Touring helmet &#183; BIKEMATE.NET \u0e0a\u0e49\u0e2d\u0e1b\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 | GIVI | FIVE advanced Gloves | DAYTONA | TANAX","og_url":"https:\/\/www.bikemate.net\/en\/tag\/touring-helmet\/","og_site_name":"BIKEMATE.NET \u0e0a\u0e49\u0e2d\u0e1b\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 | GIVI | FIVE advanced Gloves | DAYTONA | TANAX","og_image":[{"width":800,"height":534,"url":"https:\/\/www.bikemate.net\/wp-content\/uploads\/2020\/09\/bikemate-social-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@bikematenet","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.bikemate.net\/en\/tag\/touring-helmet\/","url":"https:\/\/www.bikemate.net\/en\/tag\/touring-helmet\/","name":"Touring helmet &#183; BIKEMATE.NET \u0e0a\u0e49\u0e2d\u0e1b\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e15\u0e48\u0e07\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48 \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e42\u0e25\u0e01 | GIVI | FIVE advanced Gloves | DAYTONA | TANAX","isPartOf":{"@id":"https:\/\/www.bikemate.net\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.bikemate.net\/en\/tag\/touring-helmet\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bikemate.net\/en\/tag\/touring-helmet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bikemate.net\/en\/"},{"@type":"ListItem","position":2,"name":"Touring helmet"}]},{"@type":"WebSite","@id":"https:\/\/www.bikemate.net\/en\/#website","url":"https:\/\/www.bikemate.net\/en\/","name":"BIKEMATE.NET","description":"","publisher":{"@id":"https:\/\/www.bikemate.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bikemate.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.bikemate.net\/en\/#organization","name":"BIKEMATE.NET","url":"https:\/\/www.bikemate.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.bikemate.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.bikemate.net\/wp-content\/uploads\/2020\/07\/bikemate-logo-bigbg.png","contentUrl":"https:\/\/www.bikemate.net\/wp-content\/uploads\/2020\/07\/bikemate-logo-bigbg.png","width":460,"height":116,"caption":"BIKEMATE.NET"},"image":{"@id":"https:\/\/www.bikemate.net\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BIKEMATE.NET\/","https:\/\/x.com\/bikematenet","https:\/\/www.instagram.com\/bikematenet"]}]}},"_links":{"self":[{"href":"https:\/\/www.bikemate.net\/en\/wp-json\/wp\/v2\/tags\/2562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bikemate.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.bikemate.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.bikemate.net\/en\/wp-json\/wp\/v2\/posts?tags=2562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}